{"id":9266,"date":"2014-01-28T13:52:07","date_gmt":"2014-01-28T15:52:07","guid":{"rendered":"http:\/\/blogdaandreasimonetti.com.br\/?p=9266"},"modified":"2018-05-25T08:53:00","modified_gmt":"2018-05-25T11:53:00","slug":"pen-drives-do-futuro","status":"publish","type":"post","link":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/","title":{"rendered":"Pen Drives do Futuro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg\" alt=\"1\" width=\"720\" height=\"333\" class=\"aligncenter size-full wp-image-9267\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2014\/01\/13.jpg 720w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2014\/01\/13-300x138.jpg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>A Tecnologia se tornou a grande aliada e melhor amiga dos homens do futuro. Deparamos-nos a cada dia com uma nova cria\u00e7\u00e3o para que facilite e d\u00ea praticidade aos nossos dias corridos. Sou apaixonada pela criatividade e com seu desenvolvimento de acordo com o tempo. Parece que a cada dia que passa os segundos diminuem e nem vemos o tempo passar. Assim a tecnologia nos ajuda a registrar momentos que muitas vezes passam despercebidos. <\/p>\n<p>Hoje vim falar um pouquinho de uma inova\u00e7\u00e3o sensacional a jun\u00e7\u00e3o de pen drive com post-it. Sim eu sou uma pessoa viciada em post-it e amo coloc\u00e1-los por todos os cantos com lembretes relevantes. Na minha profiss\u00e3o trabalhamos com datas sazonais e al\u00e9m do post-it o pen drive \u00e9 muito importante para armazenamento de materiais e pe\u00e7as.<\/p>\n<p>Uma empresa indiana a <a href=\"http:\/\/asdsdesign.com\/\"><strong>ASDS Design<\/strong><\/a> desenvolveu o post-it ou pen drives do futuro. Uma mistura que deu super certo e criou um produto mega funcional. Nele voc\u00ea pode armazenar seus lembretes de forma digital atrav\u00e9s de leitura \u00f3ptica chamada de ODTS (Optical Data Transfer Surface) e n\u00e3o a USB como conhecemos. Os arquivos podem ser transferidos a um computador de forma f\u00e1cil possibilitando tamb\u00e9m que voc\u00ea escreva em sua parte de \u201cpapel\u201d com caneta lembrando um post-it tradicional. <\/p>\n<p>Os <a href=\"http:\/\/datastickies.com\/index.html\"><strong>DataStickies<\/strong><\/a> \u00e9 feito de um produto chamado grafeno que o torna muito leve e fino. Al\u00e9m disso, ele ainda possui v\u00e1rios tamanhos de armazenamento como um pen drive normal. O design do produto faturou o pr\u00eamio Red Dot Award de 2014 a empresa. Abaixo coloquei algumas fotos do produto que \u00e9 divulgado no site e vamos torcer para que chegue logo ao Brasil. Para quem quiser saber mais sobre o produto os links deste post est\u00e3o direcionados para o site da empresa e para o site oficial do produto fiquem a vontade!!!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/pen.jpg\" alt=\"pen\" width=\"720\" height=\"3050\" class=\"aligncenter size-full wp-image-9268\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Tecnologia se tornou a grande aliada e melhor amiga dos homens do futuro. Deparamos-nos a cada dia com uma nova cria\u00e7\u00e3o para que facilite e d\u00ea praticidade aos nossos&hellip;<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1508,3],"tags":[942,590,1401,1402,1403,2324],"class_list":["post-9266","post","type-post","status-publish","format-standard","hentry","category-destaque","category-moda","tag-design","tag-gadgets","tag-pen-drive","tag-post-it","tag-postit","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pen Drives do Futuro - Andrea Simonetti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pen Drives do Futuro - Andrea Simonetti\" \/>\n<meta property=\"og:description\" content=\"A Tecnologia se tornou a grande aliada e melhor amiga dos homens do futuro. Deparamos-nos a cada dia com uma nova cria\u00e7\u00e3o para que facilite e d\u00ea praticidade aos nossos&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrea Simonetti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogdaandreasimonetti\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/blogdaandreasimonetti\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-28T15:52:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-25T11:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg\" \/>\n<meta name=\"author\" content=\"Andrea Simonetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Andrea_Simoneti\" \/>\n<meta name=\"twitter:site\" content=\"@Andrea_Simoneti\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Simonetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pen Drives do Futuro - Andrea Simonetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/","og_locale":"pt_BR","og_type":"article","og_title":"Pen Drives do Futuro - Andrea Simonetti","og_description":"A Tecnologia se tornou a grande aliada e melhor amiga dos homens do futuro. Deparamos-nos a cada dia com uma nova cria\u00e7\u00e3o para que facilite e d\u00ea praticidade aos nossos&hellip;","og_url":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/","og_site_name":"Andrea Simonetti","article_publisher":"https:\/\/www.facebook.com\/blogdaandreasimonetti\/","article_author":"https:\/\/www.facebook.com\/blogdaandreasimonetti\/","article_published_time":"2014-01-28T15:52:07+00:00","article_modified_time":"2018-05-25T11:53:00+00:00","og_image":[{"url":"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg","type":"","width":"","height":""}],"author":"Andrea Simonetti","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Andrea_Simoneti","twitter_site":"@Andrea_Simoneti","twitter_misc":{"Escrito por":"Andrea Simonetti","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/","url":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/","name":"Pen Drives do Futuro - Andrea Simonetti","isPartOf":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/#primaryimage"},"image":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/#primaryimage"},"thumbnailUrl":"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg","datePublished":"2014-01-28T15:52:07+00:00","dateModified":"2018-05-25T11:53:00+00:00","author":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/254f763c24ac288e27ea738a7366ad2a"},"breadcrumb":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/#primaryimage","url":"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg","contentUrl":"http:\/\/blogdaandreasimonetti.com.br\/wp-content\/uploads\/2014\/01\/13.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/andreasimonetti.com.br\/blog\/pen-drives-do-futuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/andreasimonetti.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Pen Drives do Futuro"}]},{"@type":"WebSite","@id":"https:\/\/andreasimonetti.com.br\/blog\/#website","url":"https:\/\/andreasimonetti.com.br\/blog\/","name":"Andrea Simonetti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreasimonetti.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/254f763c24ac288e27ea738a7366ad2a","name":"Andrea Simonetti","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/04\/andrea-simonetti-96x96.png","contentUrl":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/04\/andrea-simonetti-96x96.png","caption":"Andrea Simonetti"},"description":"Sou formada em Administra\u00e7\u00e3o de Empresas, Produ\u00e7\u00e3o de Moda pelo SENAC e Consultoria de Estilo. Sou fascinada por moda desde sempre, adoro ver as pessoas produzidas e de bem com a vida. Moda \u00e9 o meu assunto preferido. Comecei meu blog em 2011, ele cresceu e hoje \u00e9 um site bem mais abrangente, onde eu falo sobre moda e meu trabalho de consultora de estilo. E falo tamb\u00e9m sobre a minha experi\u00eancia de vida. Mas antes de tudo, acredito num Deus Soberano que nos guia e aben\u00e7oa, o tempo todo!","sameAs":["https:\/\/www.andreasimonetti.com.br\/","https:\/\/www.facebook.com\/blogdaandreasimonetti\/","https:\/\/www.instagram.com\/andrea_simonetti\/","https:\/\/br.pinterest.com\/BlogAndrea\/","https:\/\/x.com\/https:\/\/twitter.com\/Andrea_Simoneti"],"url":"https:\/\/andreasimonetti.com.br\/blog\/author\/andrea\/"}]}},"_links":{"self":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts\/9266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/comments?post=9266"}],"version-history":[{"count":0,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts\/9266\/revisions"}],"wp:attachment":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/media?parent=9266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/categories?post=9266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/tags?post=9266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}