{"id":20003,"date":"2018-09-02T16:17:00","date_gmt":"2018-09-02T19:17:00","guid":{"rendered":"https:\/\/www.andreasimonetti.com.br\/?p=20003"},"modified":"2018-09-02T16:17:00","modified_gmt":"2018-09-02T19:17:00","slug":"corpore-promove-a-semana-da-nutricao","status":"publish","type":"post","link":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/","title":{"rendered":"Corpore promove a Semana da Nutri\u00e7\u00e3o"},"content":{"rendered":"<p>Para comemorar a Semana de Nutri\u00e7\u00e3o a <strong>Corpore<\/strong> realizou um evento muito especial.<\/p>\n<p>Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki e apresentados produtos de empresas parceiras, entre elas a Fitonatureza que ofereceu degusta\u00e7\u00e3o de suplementos nutricionais com a especialista Luciana Bertelli.<\/p>\n<p>A a\u00e7\u00e3o refor\u00e7ou o compromisso da Corpore com a sa\u00fade e o bem estar de todos os seus alunos.<\/p>\n<p>Eu, que adoro o Mundo Corpore, estive presente e tirei muitas d\u00favidas sobre a import\u00e2ncia da alimenta\u00e7\u00e3o correta para melhorar o desempenho tanto na pr\u00e1tica esportiva como nas atividades profissionais.<\/p>\n<p>Parab\u00e9ns nutricionistas !!<\/p>\n<div id=\"attachment_20004\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20004\" class=\"wp-image-20004\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40385426_1896428367079591_6004922934794125312_n.jpg\" alt=\"Andrea Simonetti \" width=\"800\" height=\"1200\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40385426_1896428367079591_6004922934794125312_n.jpg 640w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40385426_1896428367079591_6004922934794125312_n-200x300.jpg 200w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40385426_1896428367079591_6004922934794125312_n-585x878.jpg 585w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-20004\" class=\"wp-caption-text\">Ariane Aoki<\/p><\/div>\n<div id=\"attachment_20005\" style=\"width: 1880px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20005\" class=\"wp-image-20005 size-full\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o.jpg\" alt=\"Mundo Corpore Bauru\" width=\"1870\" height=\"1250\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o.jpg 1870w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-300x201.jpg 300w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-768x513.jpg 768w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-1024x684.jpg 1024w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-1170x782.jpg 1170w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-585x391.jpg 585w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40330327_1896427787079649_98196223835504640_o-263x175.jpg 263w\" sizes=\"auto, (max-width: 1870px) 100vw, 1870px\" \/><p id=\"caption-attachment-20005\" class=\"wp-caption-text\">As nutricionistas Ariane Aoki da Corpore e Luciana Bertelli da FitoNatureza.<\/p><\/div>\n<div id=\"attachment_20006\" style=\"width: 1880px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20006\" class=\"wp-image-20006 size-full\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg\" alt=\"Mundo Corpore Bauru\" width=\"1870\" height=\"1250\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg 1870w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-300x201.jpg 300w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-768x513.jpg 768w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-1024x684.jpg 1024w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-1170x782.jpg 1170w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-585x391.jpg 585w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o-263x175.jpg 263w\" sizes=\"auto, (max-width: 1870px) 100vw, 1870px\" \/><p id=\"caption-attachment-20006\" class=\"wp-caption-text\">Ariane Aoki, Rafael Rafacho e Maria Silvia Scalzo<\/p><\/div>\n<div id=\"attachment_20007\" style=\"width: 1880px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20007\" class=\"wp-image-20007 size-full\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o.jpg\" alt=\"\" width=\"1870\" height=\"1250\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o.jpg 1870w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-300x201.jpg 300w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-768x513.jpg 768w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-1024x684.jpg 1024w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-1170x782.jpg 1170w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-585x391.jpg 585w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40297184_1896427633746331_2346828069643223040_o-263x175.jpg 263w\" sizes=\"auto, (max-width: 1870px) 100vw, 1870px\" \/><p id=\"caption-attachment-20007\" class=\"wp-caption-text\">Espresso Whey &#8211; Essential Nutrition<\/p><\/div>\n<div id=\"attachment_20009\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20009\" class=\"wp-image-20009\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40304195_1896428280412933_1399543014983991296_n.jpg\" alt=\"Mundo Corpore Bauru\" width=\"800\" height=\"1200\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40304195_1896428280412933_1399543014983991296_n.jpg 640w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40304195_1896428280412933_1399543014983991296_n-200x300.jpg 200w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40304195_1896428280412933_1399543014983991296_n-585x878.jpg 585w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-20009\" class=\"wp-caption-text\">Anderson Gandara e Melissa Pontes<\/p><\/div>\n<div id=\"attachment_20010\" style=\"width: 1880px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-20010\" class=\"size-full wp-image-20010\" src=\"https:\/\/www.andreasimonetti.com.br\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o.jpg\" alt=\"\" width=\"1870\" height=\"1250\" srcset=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o.jpg 1870w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-300x201.jpg 300w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-768x513.jpg 768w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-1024x684.jpg 1024w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-1170x782.jpg 1170w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-585x391.jpg 585w, https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40319028_1896427737079654_93543636087603200_o-263x175.jpg 263w\" sizes=\"auto, (max-width: 1870px) 100vw, 1870px\" \/><p id=\"caption-attachment-20010\" class=\"wp-caption-text\">Ariane Aoki, Mariana Mello e Renan Casal<\/p><\/div>\n<p>Fotos &#8211; Renan Casal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial. Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki e apresentados produtos de empresas&hellip;<\/p>\n","protected":false},"author":7,"featured_media":20006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[2670],"tags":[2724,2589,2725],"class_list":["post-20003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bem-estar","tag-corpore-promove-a-semana-da-nutricao","tag-mundo-corpore","tag-semana-de-nutricao"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corpore promove a Semana da Nutri\u00e7\u00e3o - Andrea Simonetti<\/title>\n<meta name=\"description\" content=\"Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial.Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corpore promove a Semana da Nutri\u00e7\u00e3o - Andrea Simonetti\" \/>\n<meta property=\"og:description\" content=\"Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial.Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/\" \/>\n<meta property=\"og:site_name\" content=\"Andrea Simonetti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/blogdaandreasimonetti\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/blogdaandreasimonetti\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-02T19:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1870\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Simonetti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Andrea_Simoneti\" \/>\n<meta name=\"twitter:site\" content=\"@Andrea_Simoneti\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Simonetti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corpore promove a Semana da Nutri\u00e7\u00e3o - Andrea Simonetti","description":"Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial.Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/","og_locale":"pt_BR","og_type":"article","og_title":"Corpore promove a Semana da Nutri\u00e7\u00e3o - Andrea Simonetti","og_description":"Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial.Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki .","og_url":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/","og_site_name":"Andrea Simonetti","article_publisher":"https:\/\/www.facebook.com\/blogdaandreasimonetti\/","article_author":"https:\/\/www.facebook.com\/blogdaandreasimonetti\/","article_published_time":"2018-09-02T19:17:00+00:00","og_image":[{"width":1870,"height":1250,"url":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg","type":"image\/jpeg"}],"author":"Andrea Simonetti","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Andrea_Simoneti","twitter_site":"@Andrea_Simoneti","twitter_misc":{"Escrito por":"Andrea Simonetti","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/","url":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/","name":"Corpore promove a Semana da Nutri\u00e7\u00e3o - Andrea Simonetti","isPartOf":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/#primaryimage"},"image":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/#primaryimage"},"thumbnailUrl":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg","datePublished":"2018-09-02T19:17:00+00:00","author":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/254f763c24ac288e27ea738a7366ad2a"},"description":"Para comemorar a Semana de Nutri\u00e7\u00e3o a Corpore realizou um evento muito especial.Durante tr\u00eas dias foram realizados bate-papos com a querida nutricionista Ariane Aoki .","breadcrumb":{"@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/#primaryimage","url":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg","contentUrl":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/09\/40374954_1896427877079640_5785274334431936512_o.jpg","width":1870,"height":1250},{"@type":"BreadcrumbList","@id":"https:\/\/andreasimonetti.com.br\/blog\/corpore-promove-a-semana-da-nutricao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/andreasimonetti.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Corpore promove a Semana da Nutri\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/andreasimonetti.com.br\/blog\/#website","url":"https:\/\/andreasimonetti.com.br\/blog\/","name":"Andrea Simonetti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/andreasimonetti.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/254f763c24ac288e27ea738a7366ad2a","name":"Andrea Simonetti","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/andreasimonetti.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/04\/andrea-simonetti-96x96.png","contentUrl":"https:\/\/andreasimonetti.com.br\/blog\/wp-content\/uploads\/2018\/04\/andrea-simonetti-96x96.png","caption":"Andrea Simonetti"},"description":"Sou formada em Administra\u00e7\u00e3o de Empresas, Produ\u00e7\u00e3o de Moda pelo SENAC e Consultoria de Estilo. Sou fascinada por moda desde sempre, adoro ver as pessoas produzidas e de bem com a vida. Moda \u00e9 o meu assunto preferido. Comecei meu blog em 2011, ele cresceu e hoje \u00e9 um site bem mais abrangente, onde eu falo sobre moda e meu trabalho de consultora de estilo. E falo tamb\u00e9m sobre a minha experi\u00eancia de vida. Mas antes de tudo, acredito num Deus Soberano que nos guia e aben\u00e7oa, o tempo todo!","sameAs":["https:\/\/www.andreasimonetti.com.br\/","https:\/\/www.facebook.com\/blogdaandreasimonetti\/","https:\/\/www.instagram.com\/andrea_simonetti\/","https:\/\/br.pinterest.com\/BlogAndrea\/","https:\/\/x.com\/https:\/\/twitter.com\/Andrea_Simoneti"],"url":"https:\/\/andreasimonetti.com.br\/blog\/author\/andrea\/"}]}},"_links":{"self":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts\/20003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/comments?post=20003"}],"version-history":[{"count":0,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/posts\/20003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/media\/20006"}],"wp:attachment":[{"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/media?parent=20003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/categories?post=20003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/andreasimonetti.com.br\/blog\/wp-json\/wp\/v2\/tags?post=20003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}